{"id":371,"date":"2012-04-04T23:53:28","date_gmt":"2012-04-04T23:53:28","guid":{"rendered":"http:\/\/mayday-wien.org\/?p=371"},"modified":"2012-04-04T23:53:28","modified_gmt":"2012-04-04T23:53:28","slug":"aufruf-zur-mayday-2012","status":"publish","type":"post","link":"https:\/\/mayday.jetzt\/index.php\/2012\/04\/04\/aufruf-zur-mayday-2012\/","title":{"rendered":"Aufruf zur MAYDAY 2012"},"content":{"rendered":"<p>*** Aufruf zur Beteiligung an der MAYDAY-Parade 2012!<\/p>\n<p>Die Parade wird dieses Jahr sehr kurzfristig geplant, lange Zeit war unklar, ob sich \u00fcberhaupt eine Organisationsgruppe finden wird. Die Parade lebt davon, dass viele verschiedene Gruppen sich vor allem direkt an der Parade beteiligen. Daher rufen wir alle Interessierten auf, sich einzubringen!<\/p>\n<p>Wir freuen uns auch \u00fcber Menschen die schon im Vorfeld Energie investieren k\u00f6nnen\/wollen.<\/p>\n<p>*** Fragestellungen:<br \/>\n. Habt ihr inhaltliche Beitr\u00e4ge f\u00fcr die Parade und damit verbundene Vorschl\u00e4ge f\u00fcr Zwischenstationen?<br \/>\n. Gibt es (Aufrufe, Termine, literarische-, theoretische-, \u2026) Texte, die ihr f\u00fcr einen Folder (Textsammlung), der zur Parade erscheinen soll, bereitstellen k\u00f6nnt? (Deadline: 27. April)<br \/>\n. Wollt ihr mit einem Wagen auf der Parade mitfahren?<br \/>\n. Habt ihr sonstige Ideen und Vorschl\u00e4ge?<\/p>\n<p>Gesucht werden au\u00dferdem noch: \u00dcbersetzer*innen f\u00fcr Texte, musikalische Beitr\u00e4ge f\u00fcr den Startpunkt und zwischendurch, kreative Aktionen f\u00fcr unterwegs, Siebdruckmotive (Deadline 20. April), \u2026<\/p>\n<p>*** Wichtig ist auch: Wir suchen noch Geldquellen f\u00fcr Plakate, T-Shirts und Infomaterial sowie weitere Kosten, die im Rahmen der Parade anfallen.<\/p>\n<p>*** Vorbereitungstreffen jeden Montag<br \/>\n16. April, 23. April, 30. April um 17:30 Uhr<br \/>\nim: PerpetuuMobile 2.3 (Geibelgasse 23, 1150 Wien)<\/p>\n<p>*** Kontakt: info@mayday-wien.org<\/p>\n<p>Prek\u00e4re Gr\u00fc\u00dfe\u2026<br \/>\n\u2026 bis demn\u00e4chst! <\/p>\n","protected":false},"excerpt":{"rendered":"<p>*** Aufruf zur Beteiligung an der MAYDAY-Parade 2012! Die Parade wird dieses Jahr sehr kurzfristig geplant, lange Zeit war unklar, ob sich \u00fcberhaupt eine Organisationsgruppe finden wird. Die Parade lebt davon, dass viele verschiedene Gruppen sich vor allem direkt an der Parade beteiligen. Daher rufen wir alle Interessierten auf, sich einzubringen! Wir freuen uns auch &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/mayday.jetzt\/index.php\/2012\/04\/04\/aufruf-zur-mayday-2012\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eAufruf zur MAYDAY 2012\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-371","post","type-post","status-publish","format-standard","hentry","category-allgemein","entry"],"_links":{"self":[{"href":"https:\/\/mayday.jetzt\/index.php\/wp-json\/wp\/v2\/posts\/371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mayday.jetzt\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mayday.jetzt\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mayday.jetzt\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mayday.jetzt\/index.php\/wp-json\/wp\/v2\/comments?post=371"}],"version-history":[{"count":0,"href":"https:\/\/mayday.jetzt\/index.php\/wp-json\/wp\/v2\/posts\/371\/revisions"}],"wp:attachment":[{"href":"https:\/\/mayday.jetzt\/index.php\/wp-json\/wp\/v2\/media?parent=371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mayday.jetzt\/index.php\/wp-json\/wp\/v2\/categories?post=371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mayday.jetzt\/index.php\/wp-json\/wp\/v2\/tags?post=371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}